{"id":990350,"date":"2022-12-20T18:17:53","date_gmt":"2022-12-20T18:17:53","guid":{"rendered":"https:\/\/zaes.es\/?p=990350"},"modified":"2024-01-05T10:06:49","modified_gmt":"2024-01-05T10:06:49","slug":"diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio","status":"publish","type":"post","link":"https:\/\/zaes.es\/es_uy\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/","title":{"rendered":"Dise\u00f1o y fabricaci\u00f3n de v\u00e1lvulas de seguridad y alivio."},"content":{"rendered":"<div class=\"vgblk-rw-wrapper limit-wrapper\">\r\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/zaes.es\/wp-content\/uploads\/2022\/12\/ZAES-Diseno-y-fabricacion.jpg\" alt=\"Dise\u00f1o y fabricaci\u00f3n de v\u00e1lvulas de seguridad y alivio. \" width=\"1200\" height=\"801\" \/><\/p>\r\n<p>Los fabricantes modernos de equipos tienen una necesidad cada vez mayor de dise\u00f1ar e implementar sistemas de manejo de fluidos que garanticen la seguridad y el rendimiento. Esta necesidad se ha visto reforzada por los cada vez m\u00e1s estrictos requisitos de calidad y seguridad. Una soluci\u00f3n para satisfacer estas necesidades es la incorporaci\u00f3n de v\u00e1lvulas de seguridad y alivio.<\/p>\r\n<p><strong>Las v\u00e1lvulas de seguridad y alivi<\/strong>o son dispositivos de control de presi\u00f3n que act\u00faan para mantener una presi\u00f3n de trabajo segura dentro de un sistema de fluido. Estas v\u00e1lvulas est\u00e1n dise\u00f1adas para abrir o cerrar autom\u00e1ticamente cuando se alcanza una presi\u00f3n predeterminada para prevenir da\u00f1os al equipo y proteger a los trabajadores. Estas v\u00e1lvulas tambi\u00e9n ayudan a controlar la presi\u00f3n a lo largo de todo el sistema, permitiendo una mayor eficiencia.<\/p>\r\n<p><strong>La fabricaci\u00f3n de v\u00e1lvulas de seguridad y alivio<\/strong> requiere una gran cantidad de conocimientos t\u00e9cnicos. Los fabricantes deben tener una comprensi\u00f3n profunda de los materiales, los procesos de fabricaci\u00f3n y la tecnolog\u00eda de dise\u00f1o de v\u00e1lvulas para garantizar la calidad y la seguridad de los productos. El dise\u00f1o de estas v\u00e1lvulas debe ser aprobado por la normativa vigente en el pa\u00eds para garantizar la seguridad y la fiabilidad.<\/p>\r\n<p><strong>La incorporaci\u00f3n de v\u00e1lvulas de seguridad y alivio<\/strong> a sistemas de manejo de fluidos es una decisi\u00f3n inteligente que asegura la seguridad, el rendimiento y la eficiencia. Los fabricantes interesados \u200b\u200ben implementar estas v\u00e1lvulas deben buscar fabricantes profesionales de v\u00e1lvulas de seguridad y alivio que puedan proporcionar productos de alta calidad que cumplan con los est\u00e1ndares de seguridad y rendimiento requeridos.<\/p>\r\n<\/div><!-- .vgblk-rw-wrapper -->","protected":false},"excerpt":{"rendered":"<p>Los fabricantes modernos de equipos tienen una necesidad cada vez mayor de dise\u00f1ar e implementar sistemas de manejo de fluidos que garanticen la seguridad y el rendimiento. Esta necesidad se ha visto reforzada por los cada vez m\u00e1s estrictos requisitos de calidad y seguridad. Una soluci\u00f3n para satisfacer estas necesidades es la incorporaci\u00f3n de v\u00e1lvulas&#8230;<\/p>","protected":false},"author":1,"featured_media":990352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"inline_featured_image":false,"footnotes":""},"categories":[130],"tags":[],"class_list":["post-990350","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-noticias","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mantenimiento de las v\u00e1lvulas de seguridad y alivio. - ZAES<\/title>\n<meta name=\"description\" content=\"El mantenimiento de las v\u00e1lvulas de seguridad y alivio es vital para mantener la seguridad de la planta y el equipo. Si los equipos est\u00e1n expuestos a temperaturas extremas, presiones excesivas y condiciones de trabajo dif\u00edciles, la vida \u00fatil de los equipos se reduce considerablemente. Por lo tanto, el mantenimiento de las v\u00e1lvulas de seguridad y alivio es esencial para asegurar la seguridad, el desempe\u00f1o y la eficiencia de la planta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zaes.es\/es_uy\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mantenimiento de las v\u00e1lvulas de seguridad y alivio. - ZAES\" \/>\n<meta property=\"og:description\" content=\"El mantenimiento de las v\u00e1lvulas de seguridad y alivio es vital para mantener la seguridad de la planta y el equipo. Si los equipos est\u00e1n expuestos a temperaturas extremas, presiones excesivas y condiciones de trabajo dif\u00edciles, la vida \u00fatil de los equipos se reduce considerablemente. Por lo tanto, el mantenimiento de las v\u00e1lvulas de seguridad y alivio es esencial para asegurar la seguridad, el desempe\u00f1o y la eficiencia de la planta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zaes.es\/es_uy\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e1lvulas de Seguridad - Zaes\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-20T18:17:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-05T10:06:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zaes.es\/wp-content\/uploads\/2022\/12\/ZAES-Diseno-y-fabricacion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"801\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"acceso_zaes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"acceso_zaes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zaes.es\\\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zaes.es\\\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\\\/\"},\"author\":{\"name\":\"acceso_zaes\",\"@id\":\"https:\\\/\\\/zaes.es\\\/#\\\/schema\\\/person\\\/68a7ab1d0dc5de2a6e089449a4833087\"},\"headline\":\"Dise\u00f1o y fabricaci\u00f3n de v\u00e1lvulas de seguridad y alivio.\",\"datePublished\":\"2022-12-20T18:17:53+00:00\",\"dateModified\":\"2024-01-05T10:06:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zaes.es\\\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\\\/\"},\"wordCount\":306,\"publisher\":{\"@id\":\"https:\\\/\\\/zaes.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zaes.es\\\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zaes.es\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/ZAES-Diseno-y-fabricacion.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-UY\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zaes.es\\\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\\\/\",\"url\":\"https:\\\/\\\/zaes.es\\\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\\\/\",\"name\":\"Mantenimiento de las v\u00e1lvulas de seguridad y alivio. - ZAES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zaes.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zaes.es\\\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zaes.es\\\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zaes.es\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/ZAES-Diseno-y-fabricacion.jpg\",\"datePublished\":\"2022-12-20T18:17:53+00:00\",\"dateModified\":\"2024-01-05T10:06:49+00:00\",\"description\":\"El mantenimiento de las v\u00e1lvulas de seguridad y alivio es vital para mantener la seguridad de la planta y el equipo. Si los equipos est\u00e1n expuestos a temperaturas extremas, presiones excesivas y condiciones de trabajo dif\u00edciles, la vida \u00fatil de los equipos se reduce considerablemente. Por lo tanto, el mantenimiento de las v\u00e1lvulas de seguridad y alivio es esencial para asegurar la seguridad, el desempe\u00f1o y la eficiencia de la planta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zaes.es\\\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\\\/#breadcrumb\"},\"inLanguage\":\"es-UY\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zaes.es\\\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-UY\",\"@id\":\"https:\\\/\\\/zaes.es\\\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zaes.es\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/ZAES-Diseno-y-fabricacion.jpg\",\"contentUrl\":\"https:\\\/\\\/zaes.es\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/ZAES-Diseno-y-fabricacion.jpg\",\"width\":1200,\"height\":801,\"caption\":\"Dise\u00f1o y fabricaci\u00f3n de v\u00e1lvulas de seguridad y alivio.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zaes.es\\\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/zaes.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dise\u00f1o y fabricaci\u00f3n de v\u00e1lvulas de seguridad y alivio.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zaes.es\\\/#website\",\"url\":\"https:\\\/\\\/zaes.es\\\/\",\"name\":\"V\u00e1lvulas de Seguridad - Zaes\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zaes.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zaes.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-UY\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zaes.es\\\/#organization\",\"name\":\"V\u00e1lvulas de Seguridad - Zaes\",\"url\":\"https:\\\/\\\/zaes.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-UY\",\"@id\":\"https:\\\/\\\/zaes.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zaes.es\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/cropped-zaes-logofooter.png\",\"contentUrl\":\"https:\\\/\\\/zaes.es\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/cropped-zaes-logofooter.png\",\"width\":233,\"height\":85,\"caption\":\"V\u00e1lvulas de Seguridad - Zaes\"},\"image\":{\"@id\":\"https:\\\/\\\/zaes.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zaes.es\\\/#\\\/schema\\\/person\\\/68a7ab1d0dc5de2a6e089449a4833087\",\"name\":\"acceso_zaes\",\"sameAs\":[\"https:\\\/\\\/zaes.es\\\/new_2022\"],\"url\":\"https:\\\/\\\/zaes.es\\\/es_uy\\\/author\\\/acceso_zaes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mantenimiento de las v\u00e1lvulas de seguridad y alivio. - ZAES","description":"El mantenimiento de las v\u00e1lvulas de seguridad y alivio es vital para mantener la seguridad de la planta y el equipo. Si los equipos est\u00e1n expuestos a temperaturas extremas, presiones excesivas y condiciones de trabajo dif\u00edciles, la vida \u00fatil de los equipos se reduce considerablemente. Por lo tanto, el mantenimiento de las v\u00e1lvulas de seguridad y alivio es esencial para asegurar la seguridad, el desempe\u00f1o y la eficiencia de la planta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zaes.es\/es_uy\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/","og_locale":"es_ES","og_type":"article","og_title":"Mantenimiento de las v\u00e1lvulas de seguridad y alivio. - ZAES","og_description":"El mantenimiento de las v\u00e1lvulas de seguridad y alivio es vital para mantener la seguridad de la planta y el equipo. Si los equipos est\u00e1n expuestos a temperaturas extremas, presiones excesivas y condiciones de trabajo dif\u00edciles, la vida \u00fatil de los equipos se reduce considerablemente. Por lo tanto, el mantenimiento de las v\u00e1lvulas de seguridad y alivio es esencial para asegurar la seguridad, el desempe\u00f1o y la eficiencia de la planta.","og_url":"https:\/\/zaes.es\/es_uy\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/","og_site_name":"V\u00e1lvulas de Seguridad - Zaes","article_published_time":"2022-12-20T18:17:53+00:00","article_modified_time":"2024-01-05T10:06:49+00:00","og_image":[{"width":1200,"height":801,"url":"https:\/\/zaes.es\/wp-content\/uploads\/2022\/12\/ZAES-Diseno-y-fabricacion.jpg","type":"image\/jpeg"}],"author":"acceso_zaes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"acceso_zaes","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zaes.es\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/#article","isPartOf":{"@id":"https:\/\/zaes.es\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/"},"author":{"name":"acceso_zaes","@id":"https:\/\/zaes.es\/#\/schema\/person\/68a7ab1d0dc5de2a6e089449a4833087"},"headline":"Dise\u00f1o y fabricaci\u00f3n de v\u00e1lvulas de seguridad y alivio.","datePublished":"2022-12-20T18:17:53+00:00","dateModified":"2024-01-05T10:06:49+00:00","mainEntityOfPage":{"@id":"https:\/\/zaes.es\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/"},"wordCount":306,"publisher":{"@id":"https:\/\/zaes.es\/#organization"},"image":{"@id":"https:\/\/zaes.es\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/#primaryimage"},"thumbnailUrl":"https:\/\/zaes.es\/wp-content\/uploads\/2022\/12\/ZAES-Diseno-y-fabricacion.jpg","articleSection":["Noticias"],"inLanguage":"es-UY"},{"@type":"WebPage","@id":"https:\/\/zaes.es\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/","url":"https:\/\/zaes.es\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/","name":"Mantenimiento de las v\u00e1lvulas de seguridad y alivio. - ZAES","isPartOf":{"@id":"https:\/\/zaes.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zaes.es\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/#primaryimage"},"image":{"@id":"https:\/\/zaes.es\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/#primaryimage"},"thumbnailUrl":"https:\/\/zaes.es\/wp-content\/uploads\/2022\/12\/ZAES-Diseno-y-fabricacion.jpg","datePublished":"2022-12-20T18:17:53+00:00","dateModified":"2024-01-05T10:06:49+00:00","description":"El mantenimiento de las v\u00e1lvulas de seguridad y alivio es vital para mantener la seguridad de la planta y el equipo. Si los equipos est\u00e1n expuestos a temperaturas extremas, presiones excesivas y condiciones de trabajo dif\u00edciles, la vida \u00fatil de los equipos se reduce considerablemente. Por lo tanto, el mantenimiento de las v\u00e1lvulas de seguridad y alivio es esencial para asegurar la seguridad, el desempe\u00f1o y la eficiencia de la planta.","breadcrumb":{"@id":"https:\/\/zaes.es\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/#breadcrumb"},"inLanguage":"es-UY","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zaes.es\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/"]}]},{"@type":"ImageObject","inLanguage":"es-UY","@id":"https:\/\/zaes.es\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/#primaryimage","url":"https:\/\/zaes.es\/wp-content\/uploads\/2022\/12\/ZAES-Diseno-y-fabricacion.jpg","contentUrl":"https:\/\/zaes.es\/wp-content\/uploads\/2022\/12\/ZAES-Diseno-y-fabricacion.jpg","width":1200,"height":801,"caption":"Dise\u00f1o y fabricaci\u00f3n de v\u00e1lvulas de seguridad y alivio."},{"@type":"BreadcrumbList","@id":"https:\/\/zaes.es\/diseno-y-fabricacion-de-valvulas-de-seguridad-y-alivio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/zaes.es\/"},{"@type":"ListItem","position":2,"name":"Dise\u00f1o y fabricaci\u00f3n de v\u00e1lvulas de seguridad y alivio."}]},{"@type":"WebSite","@id":"https:\/\/zaes.es\/#website","url":"https:\/\/zaes.es\/","name":"V\u00e1lvulas de Seguridad - Zaes","description":"","publisher":{"@id":"https:\/\/zaes.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zaes.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-UY"},{"@type":"Organization","@id":"https:\/\/zaes.es\/#organization","name":"V\u00e1lvulas de Seguridad - Zaes","url":"https:\/\/zaes.es\/","logo":{"@type":"ImageObject","inLanguage":"es-UY","@id":"https:\/\/zaes.es\/#\/schema\/logo\/image\/","url":"https:\/\/zaes.es\/wp-content\/uploads\/2017\/07\/cropped-zaes-logofooter.png","contentUrl":"https:\/\/zaes.es\/wp-content\/uploads\/2017\/07\/cropped-zaes-logofooter.png","width":233,"height":85,"caption":"V\u00e1lvulas de Seguridad - Zaes"},"image":{"@id":"https:\/\/zaes.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/zaes.es\/#\/schema\/person\/68a7ab1d0dc5de2a6e089449a4833087","name":"acceso_zaes","sameAs":["https:\/\/zaes.es\/new_2022"],"url":"https:\/\/zaes.es\/es_uy\/author\/acceso_zaes\/"}]}},"_links":{"self":[{"href":"https:\/\/zaes.es\/es_uy\/wp-json\/wp\/v2\/posts\/990350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zaes.es\/es_uy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zaes.es\/es_uy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zaes.es\/es_uy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zaes.es\/es_uy\/wp-json\/wp\/v2\/comments?post=990350"}],"version-history":[{"count":11,"href":"https:\/\/zaes.es\/es_uy\/wp-json\/wp\/v2\/posts\/990350\/revisions"}],"predecessor-version":[{"id":990465,"href":"https:\/\/zaes.es\/es_uy\/wp-json\/wp\/v2\/posts\/990350\/revisions\/990465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zaes.es\/es_uy\/wp-json\/wp\/v2\/media\/990352"}],"wp:attachment":[{"href":"https:\/\/zaes.es\/es_uy\/wp-json\/wp\/v2\/media?parent=990350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zaes.es\/es_uy\/wp-json\/wp\/v2\/categories?post=990350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zaes.es\/es_uy\/wp-json\/wp\/v2\/tags?post=990350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}